{"id":21,"date":"2022-09-27T17:04:44","date_gmt":"2022-09-27T16:04:44","guid":{"rendered":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/?page_id=21"},"modified":"2022-12-08T10:58:42","modified_gmt":"2022-12-08T10:58:42","slug":"why-apollo","status":"publish","type":"page","link":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/why-apollo\/","title":{"rendered":"Why apollo"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-iframe.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-21","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Why apollo - Apollo Blinds Cardiff<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.apollo-blinds.co.uk\/cardiff\/why-apollo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Why apollo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.apollo-blinds.co.uk\/cardiff\/why-apollo\/\" \/>\n<meta property=\"og:site_name\" content=\"Cardiff\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-08T10:58:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/why-apollo\\\/\",\"url\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/why-apollo\\\/\",\"name\":\"Why apollo - Apollo Blinds Cardiff\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/#website\"},\"datePublished\":\"2022-09-27T16:04:44+00:00\",\"dateModified\":\"2022-12-08T10:58:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/why-apollo\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/why-apollo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/why-apollo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Why apollo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/#website\",\"url\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/\",\"name\":\"Cardiff\",\"description\":\"Inspiring ideas expertly delivered\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/#organization\",\"name\":\"Cardiff\",\"url\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2022\\\/09\\\/logo-apollo.png\",\"contentUrl\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2022\\\/09\\\/logo-apollo.png\",\"width\":278,\"height\":115,\"caption\":\"Cardiff\"},\"image\":{\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/cardiff\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Why apollo - Apollo Blinds Cardiff","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/why-apollo\/","og_locale":"en_GB","og_type":"article","og_title":"Why apollo","og_url":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/why-apollo\/","og_site_name":"Cardiff","article_modified_time":"2022-12-08T10:58:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/why-apollo\/","url":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/why-apollo\/","name":"Why apollo - Apollo Blinds Cardiff","isPartOf":{"@id":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/#website"},"datePublished":"2022-09-27T16:04:44+00:00","dateModified":"2022-12-08T10:58:42+00:00","breadcrumb":{"@id":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/why-apollo\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.apollo-blinds.co.uk\/cardiff\/why-apollo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/why-apollo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/"},{"@type":"ListItem","position":2,"name":"Why apollo"}]},{"@type":"WebSite","@id":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/#website","url":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/","name":"Cardiff","description":"Inspiring ideas expertly delivered","publisher":{"@id":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/#organization","name":"Cardiff","url":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/#\/schema\/logo\/image\/","url":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/wp-content\/uploads\/sites\/14\/2022\/09\/logo-apollo.png","contentUrl":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/wp-content\/uploads\/sites\/14\/2022\/09\/logo-apollo.png","width":278,"height":115,"caption":"Cardiff"},"image":{"@id":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/wp-json\/wp\/v2\/pages\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":2,"href":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/wp-json\/wp\/v2\/pages\/21\/revisions"}],"predecessor-version":[{"id":358,"href":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/wp-json\/wp\/v2\/pages\/21\/revisions\/358"}],"wp:attachment":[{"href":"https:\/\/www.apollo-blinds.co.uk\/cardiff\/wp-json\/wp\/v2\/media?parent=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}