{"id":141,"date":"2022-10-05T11:05:43","date_gmt":"2022-10-05T10:05:43","guid":{"rendered":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/?page_id=141"},"modified":"2022-12-20T10:28:52","modified_gmt":"2022-12-20T10:28:52","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-basic.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-141","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Contact - Apollo Blinds Leeds Crossgates<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Leeds Crossgates\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-20T10:28:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/contact\\\/\",\"url\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/contact\\\/\",\"name\":\"Contact - Apollo Blinds Leeds Crossgates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/#website\"},\"datePublished\":\"2022-10-05T10:05:43+00:00\",\"dateModified\":\"2022-12-20T10:28:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/contact\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/#website\",\"url\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/\",\"name\":\"Leeds Crossgates\",\"description\":\"Inspiring ideas expertly delivered\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/#organization\",\"name\":\"Leeds Crossgates\",\"url\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/wp-content\\\/uploads\\\/sites\\\/33\\\/2022\\\/09\\\/logo-apollo.png\",\"contentUrl\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/wp-content\\\/uploads\\\/sites\\\/33\\\/2022\\\/09\\\/logo-apollo.png\",\"width\":278,\"height\":115,\"caption\":\"Leeds Crossgates\"},\"image\":{\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Contact - Apollo Blinds Leeds Crossgates","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/contact\/","og_locale":"en_GB","og_type":"article","og_title":"Contact","og_url":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/contact\/","og_site_name":"Leeds Crossgates","article_modified_time":"2022-12-20T10:28:52+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/contact\/","url":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/contact\/","name":"Contact - Apollo Blinds Leeds Crossgates","isPartOf":{"@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/#website"},"datePublished":"2022-10-05T10:05:43+00:00","dateModified":"2022-12-20T10:28:52+00:00","breadcrumb":{"@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/contact\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/#website","url":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/","name":"Leeds Crossgates","description":"Inspiring ideas expertly delivered","publisher":{"@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/#organization","name":"Leeds Crossgates","url":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/#\/schema\/logo\/image\/","url":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-content\/uploads\/sites\/33\/2022\/09\/logo-apollo.png","contentUrl":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-content\/uploads\/sites\/33\/2022\/09\/logo-apollo.png","width":278,"height":115,"caption":"Leeds Crossgates"},"image":{"@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/pages\/141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/comments?post=141"}],"version-history":[{"count":5,"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/pages\/141\/revisions"}],"predecessor-version":[{"id":387,"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/pages\/141\/revisions\/387"}],"wp:attachment":[{"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/media?parent=141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}