{"id":150,"date":"2022-10-05T11:59:07","date_gmt":"2022-10-05T10:59:07","guid":{"rendered":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/?page_id=150"},"modified":"2023-03-08T12:58:22","modified_gmt":"2023-03-08T12:58:22","slug":"installation","status":"publish","type":"page","link":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/installation\/","title":{"rendered":"Installation"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-installation.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-150","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Installation - Apollo Blinds Leeds Crossgates<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/installation\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Installation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/installation\/\" \/>\n<meta property=\"og:site_name\" content=\"Leeds Crossgates\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-08T12:58:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/installation\\\/\",\"url\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/installation\\\/\",\"name\":\"Installation - Apollo Blinds Leeds Crossgates\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/#website\"},\"datePublished\":\"2022-10-05T10:59:07+00:00\",\"dateModified\":\"2023-03-08T12:58:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/installation\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/installation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/installation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Installation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/#website\",\"url\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/\",\"name\":\"Leeds Crossgates\",\"description\":\"Inspiring ideas expertly delivered\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/#organization\",\"name\":\"Leeds Crossgates\",\"url\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/wp-content\\\/uploads\\\/sites\\\/33\\\/2022\\\/09\\\/logo-apollo.png\",\"contentUrl\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/wp-content\\\/uploads\\\/sites\\\/33\\\/2022\\\/09\\\/logo-apollo.png\",\"width\":278,\"height\":115,\"caption\":\"Leeds Crossgates\"},\"image\":{\"@id\":\"https:\\\/\\\/www.apollo-blinds.co.uk\\\/leeds-crossgates\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Installation - Apollo Blinds Leeds Crossgates","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/installation\/","og_locale":"en_GB","og_type":"article","og_title":"Installation","og_url":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/installation\/","og_site_name":"Leeds Crossgates","article_modified_time":"2023-03-08T12:58:22+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/installation\/","url":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/installation\/","name":"Installation - Apollo Blinds Leeds Crossgates","isPartOf":{"@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/#website"},"datePublished":"2022-10-05T10:59:07+00:00","dateModified":"2023-03-08T12:58:22+00:00","breadcrumb":{"@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/installation\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/installation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/installation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/"},{"@type":"ListItem","position":2,"name":"Installation"}]},{"@type":"WebSite","@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/#website","url":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/","name":"Leeds Crossgates","description":"Inspiring ideas expertly delivered","publisher":{"@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/#organization","name":"Leeds Crossgates","url":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/#\/schema\/logo\/image\/","url":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-content\/uploads\/sites\/33\/2022\/09\/logo-apollo.png","contentUrl":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-content\/uploads\/sites\/33\/2022\/09\/logo-apollo.png","width":278,"height":115,"caption":"Leeds Crossgates"},"image":{"@id":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/pages\/150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/comments?post=150"}],"version-history":[{"count":6,"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/pages\/150\/revisions"}],"predecessor-version":[{"id":411,"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/pages\/150\/revisions\/411"}],"wp:attachment":[{"href":"https:\/\/www.apollo-blinds.co.uk\/leeds-crossgates\/wp-json\/wp\/v2\/media?parent=150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}